{"id":199,"count":1,"description":"","link":"https:\/\/www.mechstream.com\/es\/tag\/one-way-clutch\/","name":"Embrague unidireccional","slug":"one-way-clutch","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.mechstream.com\/es\/wp-json\/wp\/v2\/tags\/199","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mechstream.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.mechstream.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.mechstream.com\/es\/wp-json\/wp\/v2\/posts?tags=199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}