{"id":5000,"count":1,"description":"","link":"https:\/\/www.mechstream.com\/es\/tag\/air-dryer\/","name":"air dryer","slug":"air-dryer","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.mechstream.com\/es\/wp-json\/wp\/v2\/tags\/5000","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mechstream.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.mechstream.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.mechstream.com\/es\/wp-json\/wp\/v2\/posts?tags=5000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}