{"id":3567,"count":1,"description":"","link":"https:\/\/www.mechstream.com\/fr\/tag\/mechanical-measurement-tools\/","name":"Outils de mesure m\u00e9caniques","slug":"mechanical-measurement-tools","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.mechstream.com\/fr\/wp-json\/wp\/v2\/tags\/3567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mechstream.com\/fr\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.mechstream.com\/fr\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.mechstream.com\/fr\/wp-json\/wp\/v2\/posts?tags=3567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}