{"id":2236,"count":1,"description":"","link":"https:\/\/www.mechstream.com\/pt\/tag\/japanese-design\/","name":"design japon\u00eas","slug":"japanese-design","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.mechstream.com\/pt\/wp-json\/wp\/v2\/tags\/2236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mechstream.com\/pt\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.mechstream.com\/pt\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.mechstream.com\/pt\/wp-json\/wp\/v2\/posts?tags=2236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}