{"id":4911,"count":1,"description":"","link":"https:\/\/www.mechstream.com\/pt\/tag\/wheel-rim-drawing\/","name":"wheel rim drawing","slug":"wheel-rim-drawing","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.mechstream.com\/pt\/wp-json\/wp\/v2\/tags\/4911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mechstream.com\/pt\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.mechstream.com\/pt\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.mechstream.com\/pt\/wp-json\/wp\/v2\/posts?tags=4911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}